{"id":477435,"date":"2022-01-07T10:10:05","date_gmt":"2022-01-07T15:10:05","guid":{"rendered":"https:\/\/mymodernmet.com\/aunty-moser-earliest-born-people-photographed\/"},"modified":"2022-01-07T12:04:19","modified_gmt":"2022-01-07T17:04:19","slug":"aunty-moser-persona-mas-antigua-fotografiada","status":"publish","type":"post","link":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/","title":{"rendered":"&#8220;Aunty Moser&#8221;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada"},"content":{"rendered":"<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Say hello to Aunty Moser, the whiskered centenarian who was born 271 years ago &#8211; all the way back in 1749 &#8211; & photographed here at the age of 103. She is one of the earliest-born people ever to have been photographed, sharing that distinction with Conrad Heyer, also born in 1749. <a href=\"https:\/\/t.co\/TnNKHygPNF\">pic.twitter.com\/TnNKHygPNF<\/a><\/p>\n<p>&mdash; BabelColour (@StuartHumphryes) <a href=\"https:\/\/twitter.com\/StuartHumphryes\/status\/1236054103849144321?ref_src=twsrc%5Etfw\">March 6, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><em>Saluda a la Aunty Moser, la centenaria de bigotes que naci&oacute; hace 271 a&ntilde;os, en 1749, y fue fotografiada aqu&iacute; a la edad de 103 a&ntilde;os. Es una de las primeras personas con los nacimientos m&aacute;s tempranos en ser fotografiada, y comparte esa distinci&oacute;n con Conrad Heyer, tambi&eacute;n nacido en 1749.<\/em><\/p>\n<p>El desarrollo de la fotograf&iacute;a en el siglo XIX cambi&oacute; el arte del retrato. Si bien los aguafuertes, pinturas y bocetos siguieron siendo algo com&uacute;n, los primeros retratos fotogr&aacute;ficos comenzaron a capturarse en placas de daguerrotipo. Este nuevo m&eacute;todo se extendi&oacute; r&aacute;pida y ampliamente, de modo que a mediados de siglo un retrato de estudio era accesible para personas de clase media. Estos retratos eran una nueva forma de documentar la historia y su gente, desde presidentes famosos hasta gente com&uacute;n. De hecho, un <a href=\"https:\/\/www.cowanauctions.com\/lot\/sixth-plate-daguerreotype-of-aunty-moser-103-years-of-age-146236\" target=\"_blank\" rel=\"noopener\">peque&ntilde;o daguerrotipo<\/a> subastado por Cowan's Auctions en 2014 es una parte especial, aunque misteriosa, de la historia: una mujer de 103 a&ntilde;os identificada solo como <em><strong>Aunty Moser<\/strong><\/em> o la &#8220;t&iacute;a Moser&#8221;. Nacida en 1749, es una de las personas m&aacute;s antiguas en ser fotografiada.<\/p>\n<p>La imagen de <em>Aunty Moser<\/em> es un daguerrotipo de 1\/6 de placa, una imagen peque&ntilde;a y &uacute;nica en una placa de vidrio enmarcada en una peque&ntilde;a caja de viaje. La imagen est&aacute; fechada en noviembre de 1852 con una peque&ntilde;a anotaci&oacute;n que tambi&eacute;n menciona sus 103 a&ntilde;os de edad. Esto sit&uacute;a su nacimiento en 1749. Si es correcto, la t&iacute;a Moser naci&oacute; solo 133 a&ntilde;os despu&eacute;s de la muerte de William Shakespeare en 1616. Por el contrario, su nacimiento precede la de Barack Obama en 1961 por 212 a&ntilde;os. La larga vida de la t&iacute;a Moser la hizo destacar en una &eacute;poca en la que la <a href=\"https:\/\/mappinghistory.uoregon.edu\/english\/US\/US39-01.html\" target=\"_blank\" rel=\"noopener\">esperanza de vida<\/a> era de unos 60 a&ntilde;os para las mujeres que sobrevivieron a la peligrosa infancia. Hoy, es su proximidad a un pasado aparentemente distante lo que hace que su retrato sea tan interesante.<\/p>\n<p><em>Aunty Moser<\/em> compite con varios otros por el t&iacute;tulo del retrato de la persona m&aacute;s antigua del mundo. Puede ser dif&iacute;cil verificar las fechas de nacimiento, por lo que es dif&iacute;cil pronunciar un ganador definitivo. Tambi&eacute;n se cree que <strong>Conrad Heyer<\/strong> naci&oacute; en 1749 en Waldoboro, Maine. Un veterano de la Guerra Revolucionaria, pos&oacute; para su retrato alrededor de 1852, varios a&ntilde;os antes de su muerte en 1856. Otro ejemplo es el retrato de <strong>Caesar<\/strong>, un hombre que sobrevivi&oacute; a la esclavitud y que viv&iacute;a en el norte del estado de Nueva York. Caesar pudo haber nacido en 1737, y se sabe que muri&oacute; en 1852, lo que le dar&iacute;a 115 a&ntilde;os en el momento de su muerte. Su retrato fue tomado en 1851. Si su a&ntilde;o de nacimiento es correcto, C&eacute;sar es, con mucho, con el nacimiento m&aacute;s temprano en ser fotografiada. Se desconoce mucho sobre su vida, pero tambi&eacute;n se cree que fue una de las &uacute;ltimas personas que resid&iacute;an en el estado de Nueva York en ser esclavizado y luego liberado.<\/p>\n<p>Las fotograf&iacute;as ayudan a revivir el pasado. Si bien el siglo XVIII puede parecer mucho tiempo atr&aacute;s, el medio familiar de la fotograf&iacute;a nos recuerda cu&aacute;n cerca en el tiempo est&aacute; realmente el pasado y cu&aacute;nto cambio puede abarcar una vida.<\/p>\n<h2>Una mujer de 103 a&ntilde;os conocida como <em>Aunty Moser<\/em> o &#8220;la t&iacute;a Moser&#8221; puede ser una de las personas m&aacute;s antiguas que hayan sido fotografiadas. Probablemente naci&oacute; en 1749.<\/h2>\n<div id=\"attachment_476325\" style=\"width: 610px\" class=\"wp-caption alignnone\"><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-476325\" class=\"lazyload size-full wp-image-476325\" src=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg\" alt=\"Conrad Heyer Daguerreotype\" width=\"600\" height=\"681\" srcset=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg 600w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1-264x300.jpeg 264w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1-150x170.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-476325\" class=\"lazyload size-full wp-image-476325\" src=\"data:image\/svg+xml,&lt;svg xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; viewBox=&quot;0 0 600 681&quot;&gt;&lt;\/svg&gt;\" data-src=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg\" alt=\"Conrad Heyer Daguerreotype\" width=\"600\" height=\"681\" data-srcset=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg 600w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1-264x300.jpeg 264w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1-150x170.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-476325\" class=\"wp-caption-text\">Daguerrotipo de Conrad Heyer. Se pensaba que Heyer naci&oacute; en 1749, se sabe que luch&oacute; en la Guerra de Independencia de Estados Unidos y muri&oacute; en 1856. (Foto: Conrad Heyer, Waldoboro, ca. 1852, Item 13423, Coll. 443, Caja 14\/7, Sociedad Hist&oacute;rica de Maine v&iacute;a <a href=\"https:\/\/www.mainememory.net\/artifact\/13423\" target=\"_blank\" rel=\"noopener noreferrer\">MaineMemory.Net<\/a>, <a href=\"http:\/\/rightsstatements.org\/vocab\/NoC-CR\/1.0\/\" target=\"_blank\" rel=\"noopener\">no copyright<\/a>)<\/p><\/div>\n<h2>Otros centenarios que compiten por el t&iacute;tulo incluyen a Caesar, un hombre que que sobrevivi&oacute; a la esclavitud y vivi&oacute; en el estado de Nueva York, y Conrad Heyer, un veterano de la Guerra de Independencia de Estados Unidos originario de Maine.<\/h2>\n<div id=\"attachment_476328\" style=\"width: 610px\" class=\"wp-caption alignnone\"><noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-476328\" class=\"lazyload size-full wp-image-476328\" src=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1.jpeg\" alt=\"Daguerreotype of Caesar 1851\" width=\"600\" height=\"686\" srcset=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1.jpeg 600w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1-262x300.jpeg 262w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1-150x172.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><img decoding=\"async\" aria-describedby=\"caption-attachment-476328\" class=\"lazyload size-full wp-image-476328\" src=\"data:image\/svg+xml,&lt;svg xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; viewBox=&quot;0 0 600 686&quot;&gt;&lt;\/svg&gt;\" data-src=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1.jpeg\" alt=\"Daguerreotype of Caesar 1851\" width=\"600\" height=\"686\" data-srcset=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1.jpeg 600w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1-262x300.jpeg 262w, https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/Daguerreotype-of-Caesar-1851-1-150x172.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-476328\" class=\"wp-caption-text\">Daguerrotipo de Caesar 1851, un hombre esclavizado en el norte del estado de Nueva York. Se pensaba que Caesar naci&oacute; en 1737 y muri&oacute; en 1852 un a&ntilde;o despu&eacute;s de que se tomara la fotograf&iacute;a. (Foto: Sociedad Hist&oacute;rica de Nueva York v&iacute;a <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Daguerreotype_of_Caesar_-_A_Slave;_1851.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">Wikimedia Commons<\/a>, Dominio p&uacute;blico)<\/p><\/div>\n<h2><span style=\"text-decoration: underline;\">Art&iacute;culos relacionados:<\/span><\/h2>\n<p><a href=\"https:\/\/mymodernmet.com\/es\/fotografia-cianotipia\/\">Cianotipia: el ingenioso proceso que dio color a la fotograf&iacute;a hace 170 a&ntilde;os<\/a><\/p>\n<p><a href=\"https:\/\/mymodernmet.com\/es\/fotos-atico-susan-b-anthony\/\">Hombre descubre un &aacute;tico lleno de fotos hist&oacute;ricas, incluyendo una de Susan B. Anthony<\/a><\/p>\n<p><a href=\"https:\/\/mymodernmet.com\/es\/historia-fotoperiodismo\/\">La historia del fotoperiodismo: c&oacute;mo la fotograf&iacute;a cambi&oacute; la forma en que recibimos las noticias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Say hello to Aunty Moser, the whiskered centenarian who was born 271 years ago &#8211; all the way back in 1749 &#8211; &#038; photographed here at the age of 103. She is one of the earliest-born people ever to have been photographed, sharing that distinction with Conrad Heyer, also born in 1749. pic.twitter.com\/TnNKHygPNF &mdash; BabelColour [&hellip;]<\/p>\n","protected":false},"author":320,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_wp_convertkit_post_meta":{"form":"1558017","landing_page":"","tag":"0"},"_ef_editorial_meta_date_first-draft-date":"","_ef_editorial_meta_paragraph_assignment":"","_ef_editorial_meta_checkbox_needs-photo":"","_ef_editorial_meta_number_word-count":"","footnotes":""},"categories":[168410,168423],"tags":[393662,373689,393663,389873,389878,175724,175690],"class_list":["post-477435","post","type-post","status-publish","format-standard","hentry","category-historia","category-retrato-fotografico","tag-aunty-moser-es","tag-caesar-es","tag-conrad-heyer-es","tag-daguerreotype-es","tag-daguerrotipo","tag-historia-de-la-fotografia","tag-history-of-photography-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Aunty Moser&quot;: la persona m\u00e1s antigua que haya sido fotografiada<\/title>\n<meta name=\"description\" content=\"Una mujer de 103 a\u00f1os conocida como Aunty Moser o &quot;la t\u00eda Moser&quot; puede ser una de las personas m\u00e1s antiguas que hayan sido fotografiadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Aunty Moser&quot;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada\" \/>\n<meta property=\"og:description\" content=\"Ten\u00eda 103 a\u00f1os cuando fue fotografiada en 1852, lo que podr\u00eda convertirla en la persona con el nacimiento m\u00e1s temprano en ser fotografiada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/\" \/>\n<meta property=\"og:site_name\" content=\"My Modern Met en Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mymodernmet\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T15:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-07T17:04:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/aunty-moser-oldest-person-photographed-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Regina Sienra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua en ser fotografiada\" \/>\n<meta name=\"twitter:description\" content=\"Ten\u00eda 103 a\u00f1os cuando fue fotografiada en 1852, lo que podr\u00eda convertirla en la persona con el nacimiento m\u00e1s temprano en ser fotografiada.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/aunty-moser-oldest-person-photographed-thumbnail.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@mymodernmet\" \/>\n<meta name=\"twitter:site\" content=\"@mymodernmetes\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Regina Sienra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/\"},\"author\":{\"name\":\"Regina Sienra\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#\\\/schema\\\/person\\\/968140d08ad6b9d778e1ad2f37ffe3f7\"},\"headline\":\"&#8220;Aunty Moser&#8221;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada\",\"datePublished\":\"2022-01-07T15:10:05+00:00\",\"dateModified\":\"2022-01-07T17:04:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/\"},\"wordCount\":865,\"publisher\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/conrad-heyer-1.jpeg\",\"keywords\":[\"aunty moser\",\"caesar\",\"conrad heyer\",\"daguerreotype\",\"daguerrotipo\",\"historia de la fotograf\u00eda\",\"history of photography\"],\"articleSection\":[\"Historia\",\"Retrato fotogr\u00e1fico\"],\"inLanguage\":\"es-ES\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/\",\"name\":\"\\\"Aunty Moser\\\": la persona m\u00e1s antigua que haya sido fotografiada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/conrad-heyer-1.jpeg\",\"datePublished\":\"2022-01-07T15:10:05+00:00\",\"dateModified\":\"2022-01-07T17:04:19+00:00\",\"description\":\"Una mujer de 103 a\u00f1os conocida como Aunty Moser o \\\"la t\u00eda Moser\\\" puede ser una de las personas m\u00e1s antiguas que hayan sido fotografiadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/conrad-heyer-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/conrad-heyer-1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/aunty-moser-persona-mas-antigua-fotografiada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia\",\"item\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/categoria\\\/historia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Aunty Moser&#8221;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/\",\"name\":\"My Modern Met\",\"description\":\"The Big City That Celebrates Creative Ideas\",\"publisher\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#organization\"},\"alternateName\":\"My Modern Met\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#organization\",\"name\":\"My Modern Met\",\"alternateName\":\"My Modern Met\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/tumblr-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mymodernmet.com\\\/wp\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/tumblr-logo.jpg\",\"width\":600,\"height\":600,\"caption\":\"My Modern Met\"},\"image\":{\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mymodernmet\",\"https:\\\/\\\/x.com\\\/mymodernmet\",\"https:\\\/\\\/www.instagram.com\\\/mymodernmet\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3811009?trk=tyah&amp;amp;amp;trkInfo=clickedVertical:company,clickedEntityId:3811009,idx:2-1-2,tarId:1484473853378,tas:my modern\",\"https:\\\/\\\/www.pinterest.com\\\/mymodernmet\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCmiC4DC-xa6rqVJeNiRWDcQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/#\\\/schema\\\/person\\\/968140d08ad6b9d778e1ad2f37ffe3f7\",\"name\":\"Regina Sienra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g\",\"caption\":\"Regina Sienra\"},\"description\":\"Regina Sienra es colaboradora y redactora en espa\u00f1ol para My Modern Met. Periodista y traductora originaria de la Ciudad de M\u00e9xico. Es egresada de la Universidad Nacional Aut\u00f3noma de M\u00e9xico, donde curs\u00f3 la licenciatura en Ciencias de la Comunicaci\u00f3n con especialidad en Periodismo. Su pasi\u00f3n por escribir sobre las artes visuales, la m\u00fasica, el cine, la literatura y el teatro ha dado vida a una carrera de casi 10 a\u00f1os en diversos medios culturales de M\u00e9xico, Estados Unidos y Canad\u00e1.\",\"url\":\"https:\\\/\\\/mymodernmet.com\\\/es\\\/author\\\/regina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Aunty Moser\": la persona m\u00e1s antigua que haya sido fotografiada","description":"Una mujer de 103 a\u00f1os conocida como Aunty Moser o \"la t\u00eda Moser\" puede ser una de las personas m\u00e1s antiguas que hayan sido fotografiadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/","og_locale":"es_ES","og_type":"article","og_title":"\"Aunty Moser\": la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada","og_description":"Ten\u00eda 103 a\u00f1os cuando fue fotografiada en 1852, lo que podr\u00eda convertirla en la persona con el nacimiento m\u00e1s temprano en ser fotografiada.","og_url":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/","og_site_name":"My Modern Met en Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/mymodernmet","article_published_time":"2022-01-07T15:10:05+00:00","article_modified_time":"2022-01-07T17:04:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/aunty-moser-oldest-person-photographed-thumbnail.jpg","type":"image\/jpeg"}],"author":"Regina Sienra","twitter_card":"summary_large_image","twitter_title":"La mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua en ser fotografiada","twitter_description":"Ten\u00eda 103 a\u00f1os cuando fue fotografiada en 1852, lo que podr\u00eda convertirla en la persona con el nacimiento m\u00e1s temprano en ser fotografiada.","twitter_image":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/aunty-moser-oldest-person-photographed-thumbnail.jpg","twitter_creator":"@mymodernmet","twitter_site":"@mymodernmetes","twitter_misc":{"Written by":"Regina Sienra","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#article","isPartOf":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/"},"author":{"name":"Regina Sienra","@id":"https:\/\/mymodernmet.com\/es\/#\/schema\/person\/968140d08ad6b9d778e1ad2f37ffe3f7"},"headline":"&#8220;Aunty Moser&#8221;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada","datePublished":"2022-01-07T15:10:05+00:00","dateModified":"2022-01-07T17:04:19+00:00","mainEntityOfPage":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/"},"wordCount":865,"publisher":{"@id":"https:\/\/mymodernmet.com\/es\/#organization"},"image":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#primaryimage"},"thumbnailUrl":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg","keywords":["aunty moser","caesar","conrad heyer","daguerreotype","daguerrotipo","historia de la fotograf\u00eda","history of photography"],"articleSection":["Historia","Retrato fotogr\u00e1fico"],"inLanguage":"es-ES","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/mymodernmet.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/","url":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/","name":"\"Aunty Moser\": la persona m\u00e1s antigua que haya sido fotografiada","isPartOf":{"@id":"https:\/\/mymodernmet.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#primaryimage"},"image":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#primaryimage"},"thumbnailUrl":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg","datePublished":"2022-01-07T15:10:05+00:00","dateModified":"2022-01-07T17:04:19+00:00","description":"Una mujer de 103 a\u00f1os conocida como Aunty Moser o \"la t\u00eda Moser\" puede ser una de las personas m\u00e1s antiguas que hayan sido fotografiadas.","breadcrumb":{"@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#primaryimage","url":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg","contentUrl":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2022\/01\/conrad-heyer-1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/mymodernmet.com\/es\/aunty-moser-persona-mas-antigua-fotografiada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mymodernmet.com\/es\/"},{"@type":"ListItem","position":2,"name":"Historia","item":"https:\/\/mymodernmet.com\/es\/categoria\/historia\/"},{"@type":"ListItem","position":3,"name":"&#8220;Aunty Moser&#8221;: la mujer de 103 a\u00f1os de edad que podr\u00eda ser la persona m\u00e1s antigua que haya sido fotografiada"}]},{"@type":"WebSite","@id":"https:\/\/mymodernmet.com\/es\/#website","url":"https:\/\/mymodernmet.com\/es\/","name":"My Modern Met","description":"The Big City That Celebrates Creative Ideas","publisher":{"@id":"https:\/\/mymodernmet.com\/es\/#organization"},"alternateName":"My Modern Met","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mymodernmet.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mymodernmet.com\/es\/#organization","name":"My Modern Met","alternateName":"My Modern Met","url":"https:\/\/mymodernmet.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mymodernmet.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2016\/12\/tumblr-logo.jpg","contentUrl":"https:\/\/mymodernmet.com\/wp\/wp-content\/uploads\/2016\/12\/tumblr-logo.jpg","width":600,"height":600,"caption":"My Modern Met"},"image":{"@id":"https:\/\/mymodernmet.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mymodernmet","https:\/\/x.com\/mymodernmet","https:\/\/www.instagram.com\/mymodernmet\/","https:\/\/www.linkedin.com\/company\/3811009?trk=tyah&amp;amp;amp;trkInfo=clickedVertical:company,clickedEntityId:3811009,idx:2-1-2,tarId:1484473853378,tas:my modern","https:\/\/www.pinterest.com\/mymodernmet\/","https:\/\/www.youtube.com\/channel\/UCmiC4DC-xa6rqVJeNiRWDcQ"]},{"@type":"Person","@id":"https:\/\/mymodernmet.com\/es\/#\/schema\/person\/968140d08ad6b9d778e1ad2f37ffe3f7","name":"Regina Sienra","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b74a6cdccb33496cc44288f3df56039aab6b761220fe8727ed3bd2e6aaad66e?s=96&d=mm&r=g","caption":"Regina Sienra"},"description":"Regina Sienra es colaboradora y redactora en espa\u00f1ol para My Modern Met. Periodista y traductora originaria de la Ciudad de M\u00e9xico. Es egresada de la Universidad Nacional Aut\u00f3noma de M\u00e9xico, donde curs\u00f3 la licenciatura en Ciencias de la Comunicaci\u00f3n con especialidad en Periodismo. Su pasi\u00f3n por escribir sobre las artes visuales, la m\u00fasica, el cine, la literatura y el teatro ha dado vida a una carrera de casi 10 a\u00f1os en diversos medios culturales de M\u00e9xico, Estados Unidos y Canad\u00e1.","url":"https:\/\/mymodernmet.com\/es\/author\/regina\/"}]}},"_links":{"self":[{"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/posts\/477435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/users\/320"}],"replies":[{"embeddable":true,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/comments?post=477435"}],"version-history":[{"count":7,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/posts\/477435\/revisions"}],"predecessor-version":[{"id":477503,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/posts\/477435\/revisions\/477503"}],"wp:attachment":[{"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/media?parent=477435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/categories?post=477435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mymodernmet.com\/es\/wp-json\/wp\/v2\/tags?post=477435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}